{"id":4679,"date":"2024-03-10T06:31:48","date_gmt":"2024-03-10T13:31:48","guid":{"rendered":"http:\/\/staging.christmasinthepark.com\/como-llegar-y-aparcar\/"},"modified":"2024-11-11T00:33:02","modified_gmt":"2024-11-11T08:33:02","slug":"como-llegar-y-aparcar","status":"publish","type":"page","link":"https:\/\/staging.christmasinthepark.com\/es\/informacion-para-visitantes\/como-llegar-y-aparcar\/","title":{"rendered":"C\u00f3mo llegar y estacionar"},"content":{"rendered":"\n<h3 class=\"wp-block-heading text-xl\">Navidad en el Parque del Centro<\/h3>\n\n\n\n<p>El tradicional acto a pie de Navidad en el Parque tiene lugar en el Parque de la Plaza de C\u00e9sar Ch\u00e1vez, en el centro de San Jos\u00e9, en el 194 de South Market Street, entre San Carlos y San Fernando. No hay aparcamiento p\u00fablico en el parque. <\/p>\n\n\n\n<p><strong>Desde Caltrain:<\/strong> Christmas in the Park est\u00e1 a 15-20 minutos y 0,7 millas a pie de la estaci\u00f3n Diridon. Sal de la estaci\u00f3n, gira a la derecha y luego a la izquierda en la calle San Fernando. Christmas in the Park se encuentra entre las calles San Fernando y San Carlos. Sal en la parada Parkcenter.   <br><strong>Metro Ligero:<\/strong> Sal en la parada de la calle Santa Clara. Camina hasta la calle San Fernando, luego camina hacia el oeste, hacia la calle Market. Christmas in the Park se encuentra entre las calles San Fernando y San Carlos.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center text-xl\">Aparcamiento City View Plaza y 50 Oeste<\/h3>\n\n\n<div class=\"wp-block-image margin-bottom-3xl\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a572d7b052af&quot;}\" data-wp-interactive=\"core\/image\" class=\"aligncenter size-full wp-lightbox-container\"><img fetchpriority=\"high\" decoding=\"async\" width=\"778\" height=\"642\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" src=\"http:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/Parking_at_CITP.webp\" alt=\"Aparcamiento City View Plaza y 50 Oeste\" class=\"wp-image-504\" srcset=\"https:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/Parking_at_CITP.webp 778w, https:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/Parking_at_CITP-300x248.webp 300w, https:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/Parking_at_CITP-768x634.webp 768w\" sizes=\"(max-width: 778px) 100vw, 778px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading has-text-align-center text-xl\">Aparcamiento del Mercado de la Plaza de San Pedro<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a572d7b0603d&quot;}\" data-wp-interactive=\"core\/image\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" width=\"830\" height=\"800\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" src=\"http:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/San-Pedro-Square-Market-Parking.webp\" alt=\"Aparcamiento del Mercado de la Plaza de San Pedro\" class=\"wp-image-510\" srcset=\"https:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/San-Pedro-Square-Market-Parking.webp 830w, https:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/San-Pedro-Square-Market-Parking-300x289.webp 300w, https:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/San-Pedro-Square-Market-Parking-768x740.webp 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div>\n\n\n<p class=\"has-text-align-center margin-bottom-3xl\">Situado unas manzanas al norte de Navidad en el Parque est\u00e1 el Mercado de la Plaza de San Pedro.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a572d7b077f9&quot;}\" data-wp-interactive=\"core\/image\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"635\" height=\"740\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" src=\"http:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/San-Jose-City-Parking-Garages-1.jpg\" alt=\"Aparcamientos de la ciudad de San Jos\u00e9\" class=\"wp-image-527\" srcset=\"https:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/San-Jose-City-Parking-Garages-1.jpg 635w, https:\/\/staging.christmasinthepark.com\/wp-content\/uploads\/2024\/03\/San-Jose-City-Parking-Garages-1-257x300.jpg 257w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\">\n<h3 class=\"wp-block-heading text-xl\">Aparcamientos de la ciudad de San Jos\u00e9<\/h3>\n\n\n\n<p>Algunos de los garajes m\u00e1s populares de Navidad en el Parque est\u00e1n a poca distancia a pie, \u00a1y puedes aparcar gratis durante 90 minutos! Las tarifas y tasas var\u00edan de un garaje a otro. Consulta las tarifas de aparcamiento en <a href=\"https:\/\/parksj.org\">https:\/\/parksj.org<\/a>.  <\/p>\n\n\n\n<p>Hay un mapa interactivo de aparcamientos disponible aqu\u00ed: <a href=\"https:\/\/parksj.org\/parking-map\/\">https:\/\/parksj.org\/parking-map\/<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Navidad en el Parque del Centro El tradicional acto a pie de Navidad en el Parque tiene lugar en el Parque de la Plaza de C\u00e9sar Ch\u00e1vez, en el centro de San Jos\u00e9, en el 194 de South Market Street, entre San Carlos y San Fernando. No hay aparcamiento p\u00fablico en el parque. Desde Caltrain: [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":4697,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4679","page","type-page","status-publish","hentry"],"acpt":{"meta":[]},"_links":{"self":[{"href":"https:\/\/staging.christmasinthepark.com\/es\/wp-json\/wp\/v2\/pages\/4679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.christmasinthepark.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.christmasinthepark.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.christmasinthepark.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.christmasinthepark.com\/es\/wp-json\/wp\/v2\/comments?post=4679"}],"version-history":[{"count":0,"href":"https:\/\/staging.christmasinthepark.com\/es\/wp-json\/wp\/v2\/pages\/4679\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/staging.christmasinthepark.com\/es\/wp-json\/wp\/v2\/pages\/4697"}],"wp:attachment":[{"href":"https:\/\/staging.christmasinthepark.com\/es\/wp-json\/wp\/v2\/media?parent=4679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}